{"id":8188,"date":"2025-12-20T08:58:04","date_gmt":"2025-12-20T08:58:04","guid":{"rendered":"https:\/\/wp.lobbywatch.ch\/?page_id=8188"},"modified":"2026-03-03T11:13:11","modified_gmt":"2026-03-03T11:13:11","slug":"mitgliedschaft","status":"publish","type":"page","link":"https:\/\/lobbywatch.ch\/fr\/mitgliedschaft\/","title":{"rendered":"Adh\u00e9sion"},"content":{"rendered":"<div id=\"fws_6a04f78a2d298\"  data-column-margin=\"default\" data-midnight=\"light\"  class=\"wpb_row vc_row-fluid vc_row full-width-content vc_row-o-equal-height vc_row-flex vc_row-o-content-top  top_padding_tablet_15pct top_padding_phone_20pct\"  style=\"padding-top: 120px; padding-bottom: -15px; \"><div class=\"row-bg-wrap\" data-bg-animation=\"none\" data-bg-animation-delay=\"\" data-bg-overlay=\"false\"><div class=\"inner-wrap row-bg-layer\" ><div class=\"row-bg viewport-desktop\"  style=\"\"><\/div><\/div><\/div><div class=\"row_col_wrap_12 col span_12 light left\">\n\t<div style=\"\" class=\"vc_col-sm-12 wpb_column column_container vc_column_container col el_spacing_0px right_padding_desktop_8pct bottom_padding_desktop_1pct\" data-using-bg=\"true\" data-overlay-color=\"true\" data-bg-cover=\"true\" data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" ><div class=\"column-image-bg-wrap column-bg-layer viewport-desktop\" data-bg-pos=\"center center\" data-bg-animation=\"none\" data-bg-overlay=\"true\"><div class=\"inner-wrap\"><div class=\"column-image-bg\" style=\" background-image: url('https:\/\/lobbywatch.ch\/wp-content\/uploads\/2025\/10\/Hero_a.jpg'); \"><\/div><\/div><\/div><div class=\"column-bg-overlay-wrap column-bg-layer\" data-bg-animation=\"none\"><div class=\"column-bg-overlay\"><\/div><div class=\"column-overlay-layer\" style=\"background: #153770; background: linear-gradient(135deg,#153770 0%,#2D99D8 100%);  opacity: 0.95; \"><\/div><\/div>\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t<div id=\"fws_6a04f78a2dc6e\" data-midnight=\"\" data-column-margin=\"default\" class=\"wpb_row vc_row-fluid vc_row inner_row  right_padding_10pct left_padding_10pct right_padding_tablet_7pct right_padding_phone_4pct left_padding_tablet_7pct left_padding_phone_4pct\"  style=\"\"><div class=\"row-bg-wrap\"> <div class=\"row-bg\" ><\/div> <\/div><div class=\"row_col_wrap_12_inner col span_12  left\">\n\t<div style=\"margin-bottom: 5px; \" class=\"vc_col-sm-12 wpb_column column_container vc_column_container col child_column no-extra-padding bottom_margin_phone_15px inherit_tablet inherit_phone\"   data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<div class=\"divider-wrap height_phone_20px\" data-alignment=\"default\"><div style=\"height: 20px;\" class=\"divider\"><\/div><\/div>\n<div class=\"wpb_text_column wpb_content_element  text_direction_ltr\" style=\" max-width: 700px; display: inline-block;\">\n\t<div class=\"wpb_wrapper\">\n\t\t<h5 style=\"text-align: left;\">Merci, renforcez le contrepoids au pouvoir<br \/>\ndes lobbies.<\/h5>\n\t<\/div>\n<\/div>\n\n\n\n\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n<\/div><\/div>\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div>\n\t\t<div id=\"fws_6a04f78a2e367\"  data-column-margin=\"100px\" data-midnight=\"dark\"  class=\"wpb_row vc_row-fluid vc_row full-width-section\"  style=\"padding-top: 0px; padding-bottom: 0px; \"><div class=\"row-bg-wrap\" data-bg-animation=\"none\" data-bg-animation-delay=\"\" data-bg-overlay=\"false\"><div class=\"inner-wrap row-bg-layer\" ><div class=\"row-bg viewport-desktop\"  style=\"\"><\/div><\/div><\/div><div class=\"row_col_wrap_12 col span_12 dark left\">\n\t<div style=\" color: #153770;\" class=\"vc_col-sm-8 wpb_column column_container vc_column_container col no-extra-padding force-desktop-text-align-left el_spacing_0px inherit_tablet inherit_phone\" data-cfc=\"true\"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t<div class=\"divider-wrap height_phone_15px\" data-alignment=\"default\"><div style=\"height: 25px;\" class=\"divider\"><\/div><\/div><div class=\"divider-wrap\" data-alignment=\"default\"><div style=\"height: 20px;\" class=\"divider\"><\/div><\/div><div id=\"fws_6a04f78a2e7dd\" data-midnight=\"\" data-column-margin=\"default\" class=\"wpb_row vc_row-fluid vc_row inner_row\"  style=\"\"><div class=\"row-bg-wrap\"> <div class=\"row-bg\" ><\/div> <\/div><div class=\"row_col_wrap_12_inner col span_12  left\">\n\t<div  class=\"vc_col-sm-12 vc_hidden-xs wpb_column column_container vc_column_container col child_column no-extra-padding column_element_direction_desktop_horizontal column_element_direction_tablet_horizontal column_element_direction_phone_horizontal el_spacing_50px inherit_tablet inherit_phone\"   data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<div class=\"nectar-cta  text_hover_color_FF4646 alignment_tablet_default alignment_phone_default display_tablet_inherit display_phone_inherit\" data-color=\"default\" data-using-bg=\"false\" data-display=\"inline\" data-style=\"underline\" data-alignment=\"left\" data-text-color=\"custom\" ><h3 style=\"color: #153770;\"> <span class=\"link_wrap\" ><a  class=\"link_text\" style=\"border-color: #153770;\" role=\"button\" href=\"https:\/\/lobbywatch.ch\/fr\/spenden\/\">Faire un don<\/a><\/span><\/h3><\/div><div class=\"nectar-cta  text_hover_color_E13535 alignment_tablet_default alignment_phone_default display_tablet_inherit display_phone_inline-block\" data-color=\"default\" data-using-bg=\"false\" data-display=\"block\" data-style=\"underline\" data-alignment=\"left\" data-text-color=\"custom\" ><h3 style=\"color: #FF4646;\"> <span class=\"link_wrap\" ><a  class=\"link_text\" style=\"border-color: #FF4646;\" role=\"button\" href=\"https:\/\/lobbywatch.ch\/fr\/mitgliedschaft\/\">Adh\u00e9sion<\/a><\/span><\/h3><\/div><div class=\"nectar-cta  text_hover_color_FF4646 alignment_tablet_default alignment_phone_default display_tablet_inherit display_phone_inline-block\" data-color=\"default\" data-using-bg=\"false\" data-display=\"block\" data-style=\"underline\" data-alignment=\"left\" data-text-color=\"custom\" ><h3 style=\"color: #153770;\"> <span class=\"link_wrap\" ><a  class=\"link_text\" style=\"border-color: #153770;\" role=\"button\" href=\"https:\/\/lobbywatch.ch\/fr\/mithelfen\/\">Participer<\/a><\/span><\/h3><\/div>\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n<\/div><\/div><div id=\"fws_6a04f78a2ee99\" data-midnight=\"\" data-column-margin=\"default\" class=\"wpb_row vc_row-fluid vc_row inner_row\"  style=\"\"><div class=\"row-bg-wrap\"> <div class=\"row-bg\" ><\/div> <\/div><div class=\"row_col_wrap_12_inner col span_12  left\">\n\t<div  class=\"vc_col-sm-12 vc_hidden-lg vc_hidden-md vc_hidden-sm wpb_column column_container vc_column_container col child_column no-extra-padding column_element_direction_desktop_horizontal column_element_direction_tablet_horizontal column_element_direction_phone_horizontal el_spacing_30px inherit_tablet inherit_phone\"   data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<div class=\"nectar-cta  text_hover_color_FF4646 alignment_tablet_default alignment_phone_default display_tablet_inherit display_phone_inherit\" data-color=\"default\" data-using-bg=\"false\" data-display=\"inline\" data-style=\"underline\" data-alignment=\"left\" data-text-color=\"custom\" ><h3 style=\"color: #153770;\"> <span class=\"link_wrap\" ><a  class=\"link_text\" style=\"border-color: #153770;\" role=\"button\" href=\"https:\/\/lobbywatch.ch\/fr\/spenden\/\">Faire un don<\/a><\/span><\/h3><\/div><div class=\"nectar-cta  text_hover_color_E13535 alignment_tablet_default alignment_phone_default display_tablet_inherit display_phone_inline-block\" data-color=\"default\" data-using-bg=\"false\" data-display=\"block\" data-style=\"underline\" data-alignment=\"left\" data-text-color=\"custom\" ><h3 style=\"color: #FF4646;\"> <span class=\"link_wrap\" ><a  class=\"link_text\" style=\"border-color: #FF4646;\" role=\"button\" href=\"https:\/\/lobbywatch.ch\/fr\/mitgliedschaft\/\">Adh\u00e9sion<\/a><\/span><\/h3><\/div><div class=\"nectar-cta  text_hover_color_FF4646 alignment_tablet_default alignment_phone_default display_tablet_inherit display_phone_inline-block\" data-color=\"default\" data-using-bg=\"false\" data-display=\"block\" data-style=\"underline\" data-alignment=\"left\" data-text-color=\"custom\" ><h3 style=\"color: #153770;\"> <span class=\"link_wrap\" ><a  class=\"link_text\" style=\"border-color: #153770;\" role=\"button\" href=\"https:\/\/lobbywatch.ch\/fr\/mithelfen\/\">Participer<\/a><\/span><\/h3><\/div>\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n<\/div><\/div><div class=\"divider-wrap\" data-alignment=\"default\"><div style=\"height: 70px;\" class=\"divider\"><\/div><\/div>\n<div class=\"wpb_text_column wpb_content_element  text_direction_ltr  vc_custom_1770036110189\" style=\" max-width: 700px; display: inline-block;\">\n\t<div class=\"wpb_wrapper\">\n\t\t<p><strong>Nos membres garantissent notre ind\u00e9pendance et nous permettent de r\u00e9aliser des en-qu\u00eates approfondies. Plus nous sommes nombreux\u00b7ses, plus notre voix en faveur de la transparence est forte.<\/strong><\/p>\n\t<\/div>\n<\/div>\n\n\n\n<div class=\"divider-wrap\" data-alignment=\"default\"><div style=\"height: 30px;\" class=\"divider\"><\/div><\/div>\n<div class=\"wpb_text_column wpb_content_element  text_direction_ltr\" style=\" max-width: 700px; display: inline-block;\">\n\t<div class=\"wpb_wrapper\">\n\t\t<div class=\"divider-wrap height_phone_15px\" data-alignment=\"default\"><\/div>\n<div class=\"wpb_text_column wpb_content_element text_direction_ltr vc_custom_1763462385644\">\n<div class=\"wpb_wrapper\">\n<h3>Vos avantages en tant que membre :<\/h3>\n<\/div>\n<\/div>\n<div class=\"nectar-fancy-ul\" data-list-icon=\"icon-salient-check\" data-animation=\"false\" data-animation-delay=\"0\" data-color=\"extra-color-2\" data-spacing=\"10px\" data-alignment=\"left\">\n<ul>\n<li><i class=\"icon-default-style icon-salient-check extra-color-2\"><\/i> Participation gratuite aux visites guid\u00e9es Lobbywatch : quatre fois par an pendant les semaines de session.<\/li>\n<li><i class=\"icon-default-style icon-salient-check extra-color-2\"><\/i> Invitation \u00e0 l\u2019assembl\u00e9e g\u00e9n\u00e9rale : participez aux d\u00e9cisions, donnez votre avis et contribuez \u00e0 fa\u00e7onner l\u2019avenir de Lobbywatch.<\/li>\n<li><i class=\"icon-default-style icon-salient-check extra-color-2\"><\/i> Newsletter Lobbywatch : restez inform\u00e9\u00b7e des derni\u00e8res enqu\u00eates, des avanc\u00e9es et des r\u00e9percussions politiques de nos actions.<\/li>\n<\/ul>\n<\/div>\n\t<\/div>\n<\/div>\n\n\n\n<div class=\"divider-wrap\" data-alignment=\"default\"><div style=\"height: 30px;\" class=\"divider\"><\/div><\/div>\n<div class=\"wpb_text_column wpb_content_element\" >\n\t<div class=\"wpb_wrapper\">\n\t\t<div class=\"wpb_text_column wpb_content_element\">\n<div class=\"wpb_wrapper\">\n<h2>Devenez membre d\u00e8s maintenant :<\/h2>\n<\/div>\n<\/div>\n\t<\/div>\n<\/div>\n\n\n\n<div class=\"divider-wrap height_phone_0px\" data-alignment=\"default\"><div style=\"height: 10px;\" class=\"divider\"><\/div><\/div><div id=\"fws_6a04f78a2f6b3\" data-midnight=\"\" data-column-margin=\"default\" class=\"wpb_row vc_row-fluid vc_row inner_row  vc_custom_1767011992224 top_padding_phone_5px\"  style=\"\"><div class=\"row-bg-wrap\"> <div class=\"row-bg\" ><\/div> <\/div><div class=\"row_col_wrap_12_inner col span_12  left\">\n\t<div style=\"margin-top: -10px; \" class=\"vc_col-sm-12 wpb_column column_container vc_column_container col child_column neg-marg no-extra-padding inherit_tablet inherit_phone\"   data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t\n\t<div class=\"wpb_raw_code wpb_raw_html wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<script type=\"text\/javascript\" src=\"https:\/\/secure.fundraisingbox.com\/app\/paymentJS?hash=20xyuk75ccr3399n\"><\/script><noscript>Veuillez activer JavaScript<\/noscript><a target=\"_blank\" href=\"https:\/\/www.fundraisingbox.com\/?utm_source=donation_form\"><img decoding=\"async\" border=\"0\" style=\"border: 0 !important; margin-left: 30px;\" src=\"https:\/\/secure.fundraisingbox.com\/images\/FundraisingBox-Logo-Widget.png\" alt=\"FundraisingBox Logo\" \/>\n\t\t<\/div>\n\t<\/div>\n\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n<\/div><\/div><div class=\"divider-wrap height_phone_40px\" data-alignment=\"default\"><div style=\"height: 100px;\" class=\"divider\"><\/div><\/div><div class=\"divider-wrap\" data-alignment=\"default\"><div style=\"height: 20px;\" class=\"divider\"><\/div><\/div><div class=\"divider-wrap height_phone_0px\" data-alignment=\"default\"><div style=\"height: 20px;\" class=\"divider\"><\/div><\/div>\n<div class=\"wpb_text_column wpb_content_element  text_direction_ltr\" style=\" max-width: 550px; display: inline-block;\">\n\t<div class=\"wpb_wrapper\">\n\t\t<h2 style=\"text-align: left;\">Questions concernant votre don ou votre adh\u00e9sion<\/h2>\n\t<\/div>\n<\/div>\n\n\n\n<div class=\"divider-wrap\" data-alignment=\"default\"><div style=\"margin-top: 12.5px; height: 2px; margin-bottom: 12.5px;\" data-width=\"100%\" data-animate=\"\" data-animation-delay=\"\" data-color=\"extra-color-2\" class=\"divider-border\"><\/div><\/div><div class=\"divider-wrap height_phone_0px\" data-alignment=\"default\"><div style=\"height: 20px;\" class=\"divider\"><\/div><\/div><div class=\"toggles accordion\" data-br=\"\" data-starting=\"closed\" data-style=\"minimal\"><div class=\"toggle accent-color\" data-inner-wrap=\"true\"><h3 class=\"toggle-title\"><a href=\"#\" role=\"button\" class=\"nectar-inherit-h5 toggle-heading\"><i role=\"presentation\" class=\"fa fa-plus-circle\"><\/i>Quels sont les modes de paiement disponibles ?<\/a><\/h3><div><div class=\"inner-toggle-wrap\">\n<div class=\"wpb_text_column wpb_content_element\" >\n\t<div class=\"wpb_wrapper\">\n\t\t<p>Carte de d\u00e9bit, carte de cr\u00e9dit, Twint, facture QR, Apple Pay, Paypal, Google Pay<\/p>\n\t<\/div>\n<\/div>\n\n\n\n<\/div><\/div><\/div><div class=\"toggle accent-color\" data-inner-wrap=\"true\"><h3 class=\"toggle-title\"><a href=\"#\" role=\"button\" class=\"nectar-inherit-h5 toggle-heading\"><i role=\"presentation\" class=\"fa fa-plus-circle\"><\/i>Comment puis-je d\u00e9duire mon don ou mon adh\u00e9sion de mes imp\u00f4ts ?<\/a><\/h3><div><div class=\"inner-toggle-wrap\">\n<div class=\"wpb_text_column wpb_content_element\" >\n\t<div class=\"wpb_wrapper\">\n\t\t<p>Lobbywatch est une association d\u2019utilit\u00e9 publique exon\u00e9r\u00e9e d\u2019imp\u00f4ts et votre don est d\u00e9-ductible des imp\u00f4ts. En d\u00e9but d\u2019ann\u00e9e, nous vous envoyons automatiquement un re\u00e7u de don pour l\u2019ann\u00e9e civile \u00e9coul\u00e9e. Vous pouvez le joindre \u00e0 votre d\u00e9claration d\u2019imp\u00f4ts.<\/p>\n\t<\/div>\n<\/div>\n\n\n\n<\/div><\/div><\/div><div class=\"toggle accent-color\" data-inner-wrap=\"true\"><h3 class=\"toggle-title\"><a href=\"#\" role=\"button\" class=\"nectar-inherit-h5 toggle-heading\"><i role=\"presentation\" class=\"fa fa-plus-circle\"><\/i>Pourquoi une adh\u00e9sion est-elle plus efficace qu\u2019un don ?<\/a><\/h3><div><div class=\"inner-toggle-wrap\">\n<div class=\"wpb_text_column wpb_content_element\" >\n\t<div class=\"wpb_wrapper\">\n\t\t<p>Les dons nous aident \u00e0 r\u00e9aliser des projets ponctuels, tandis que les adh\u00e9sions assurent notre p\u00e9rennit\u00e9. Les cotisations r\u00e9guli\u00e8res nous permettent de planifier des enqu\u00eates de longue haleine. Par ailleurs, un nombre important de membres donne plus de poids \u00e0 nos revendications politiques : nous parlons au nom d\u2019une large communaut\u00e9, et non comme une voix isol\u00e9e.<\/p>\n\t<\/div>\n<\/div>\n\n\n\n<\/div><\/div><\/div><\/div>\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n\n\t<div  class=\"vc_col-sm-4 wpb_column column_container vc_column_container col force-desktop-text-align-left el_spacing_0px\"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t<div class=\"divider-wrap height_tablet_150px height_phone_30px\" data-alignment=\"default\"><div style=\"height: 250px;\" class=\"divider\"><\/div><\/div><div id=\"fws_6a04f78a30339\" data-midnight=\"\" data-column-margin=\"default\" class=\"wpb_row vc_row-fluid vc_row inner_row\"  style=\"\"><div class=\"row-bg-wrap\"> <div class=\"row-bg\" ><\/div> <\/div><div class=\"row_col_wrap_12_inner col span_12  left\">\n\t<div style=\"\" class=\"vc_col-sm-12 wpb_column column_container vc_column_container col child_column el_spacing_0px left_padding_desktop_40px top_padding_desktop_40px right_padding_desktop_40px bottom_padding_desktop_40px\"  data-using-bg=\"true\" data-border-radius=\"10px\" data-padding-pos=\"all\" data-has-bg-color=\"true\" data-bg-color=\"#D9D9D9\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" ><div class=\"column-bg-overlay-wrap column-bg-layer\" data-bg-animation=\"none\"><div class=\"column-bg-overlay\" style=\"opacity: 1; background-color: #D9D9D9;\"><\/div><\/div>\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t\n<div class=\"wpb_text_column wpb_content_element\" >\n\t<div class=\"wpb_wrapper\">\n\t\t<h3>Ce que votre contribution rend possible:<\/h3>\n\t<\/div>\n<\/div>\n\n\n\n<div class=\"divider-wrap\" data-alignment=\"default\"><div style=\"height: 10px;\" class=\"divider\"><\/div><\/div><div class=\"nectar-fancy-ul font_size_min_13px font_size_max_15px font_size_desktop_15px\" data-list-icon=\"icon-salient-check\" data-animation=\"false\" data-animation-delay=\"0\" data-color=\"extra-color-2\" data-spacing=\"10px\" data-alignment=\"left\"> \n<ul>\n<li><strong>Stabilit\u00e9 financi\u00e8re :<\/strong>des contributions r\u00e9guli\u00e8res permettent de mener des enqu\u00eates approfondies et de mettre au jour des pratiques de lobbying probl\u00e9matiques.<\/li>\n<li><strong>Poids politique :<\/strong> plus nous comptons de membres, plus nos revendications en ma-ti\u00e8re de transparence ont de poids.<\/li>\n<li><strong>Ind\u00e9pendance :<\/strong> les membres et les dons garantissent notre ind\u00e9pendance vis-\u00e0-vis des partis politiques, des associations et des entreprises \u2013 nous pouvons ainsi rendre publiques les v\u00e9rit\u00e9s qui d\u00e9rangent.<\/li>\n<\/ul>\n <\/div>\n<div class=\"wpb_text_column wpb_content_element\" >\n\t<div class=\"wpb_wrapper\">\n\t\t<h3>Recommandez-nous :<\/h3>\n\t<\/div>\n<\/div>\n\n\n\n<div class=\"divider-wrap\" data-alignment=\"default\"><div style=\"height: 10px;\" class=\"divider\"><\/div><\/div>\n\t<div class=\"wpb_raw_code wpb_raw_html wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<div class=\"heateor_sss_sharing_container heateor_sss_horizontal_sharing\" data-heateor-ss-offset=\"0\" data-heateor-sss-href='https:\/\/lobbywatch.ch\/fr\/mitgliedschaft\/'><div class=\"heateor_sss_sharing_ul\"><a aria-label=\"Whatsapp\" class=\"heateor_sss_whatsapp\" href=\"https:\/\/api.whatsapp.com\/send?text=Mitgliedschaft%20https%3A%2F%2Flobbywatch.ch%2Ffr%2Fmitgliedschaft%2F\" title=\"Whatsapp\" rel=\"nofollow noopener\" target=\"_blank\" style=\"font-size:32px!important;box-shadow:none;display:inline-block;vertical-align:middle\"><span class=\"heateor_sss_svg\" style=\"background-color:#55eb4c;width:23px;height:23px;border-radius:999px;display:inline-block;opacity:1;float:left;font-size:32px;box-shadow:none;display:inline-block;font-size:16px;padding:0 4px;vertical-align:middle;background-repeat:repeat;overflow:hidden;padding:0;cursor:pointer;box-sizing:content-box\"><svg style=\"display:block;border-radius:999px;\" focusable=\"false\" aria-hidden=\"true\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"100%\" height=\"100%\" viewbox=\"-6 -5 40 40\"><path class=\"heateor_sss_svg_stroke heateor_sss_no_fill\" stroke=\"#fff\" stroke-width=\"2\" fill=\"none\" d=\"M 11.579798566743314 24.396926207859085 A 10 10 0 1 0 6.808479557110079 20.73576436351046\"><\/path><path d=\"M 7 19 l -1 6 l 6 -1\" class=\"heateor_sss_no_fill heateor_sss_svg_stroke\" stroke=\"#fff\" stroke-width=\"2\" fill=\"none\"><\/path><path d=\"M 10 10 q -1 8 8 11 c 5 -1 0 -6 -1 -3 q -4 -3 -5 -5 c 4 -2 -1 -5 -1 -4\" fill=\"#fff\"><\/path><\/svg><\/span><\/a><a aria-label=\"X\" class=\"heateor_sss_button_x\" href=\"https:\/\/twitter.com\/intent\/tweet?text=Mitgliedschaft&url=https%3A%2F%2Flobbywatch.ch%2Ffr%2Fmitgliedschaft%2F\" title=\"X\" rel=\"nofollow noopener\" target=\"_blank\" style=\"font-size:32px!important;box-shadow:none;display:inline-block;vertical-align:middle\"><span class=\"heateor_sss_svg heateor_sss_s__default heateor_sss_s_x\" style=\"background-color:#2a2a2a;width:23px;height:23px;border-radius:999px;display:inline-block;opacity:1;float:left;font-size:32px;box-shadow:none;display:inline-block;font-size:16px;padding:0 4px;vertical-align:middle;background-repeat:repeat;overflow:hidden;padding:0;cursor:pointer;box-sizing:content-box\"><svg width=\"100%\" height=\"100%\" style=\"display:block;border-radius:999px;\" focusable=\"false\" aria-hidden=\"true\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 32 32\"><path fill=\"#fff\" d=\"M21.751 7h3.067l-6.7 7.658L26 25.078h-6.172l-4.833-6.32-5.531 6.32h-3.07l7.167-8.19L6 7h6.328l4.37 5.777L21.75 7Zm-1.076 16.242h1.7L11.404 8.74H9.58l11.094 14.503Z\"><\/path><\/svg><\/span><\/a><a aria-label=\"Facebook\" class=\"heateor_sss_facebook\" href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https%3A%2F%2Flobbywatch.ch%2Ffr%2Fmitgliedschaft%2F\" title=\"Facebook\" rel=\"nofollow noopener\" target=\"_blank\" style=\"font-size:32px!important;box-shadow:none;display:inline-block;vertical-align:middle\"><span class=\"heateor_sss_svg\" style=\"background-color:#0765FE;width:23px;height:23px;border-radius:999px;display:inline-block;opacity:1;float:left;font-size:32px;box-shadow:none;display:inline-block;font-size:16px;padding:0 4px;vertical-align:middle;background-repeat:repeat;overflow:hidden;padding:0;cursor:pointer;box-sizing:content-box\"><svg style=\"display:block;border-radius:999px;\" focusable=\"false\" aria-hidden=\"true\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"100%\" height=\"100%\" viewbox=\"0 0 32 32\"><path fill=\"#fff\" d=\"M28 16c0-6.627-5.373-12-12-12S4 9.373 4 16c0 5.628 3.875 10.35 9.101 11.647v-7.98h-2.474V16H13.1v-1.58c0-4.085 1.849-5.978 5.859-5.978.76 0 2.072.15 2.608.298v3.325c-.283-.03-.775-.045-1.386-.045-1.967 0-2.728.745-2.728 2.683V16h3.92l-.673 3.667h-3.247v8.245C23.395 27.195 28 22.135 28 16Z\"><\/path><\/svg><\/span><\/a><a aria-label=\"Instagram\" class=\"heateor_sss_button_instagram\" href=\"https:\/\/www.instagram.com\/\" title=\"Instagram\" rel=\"nofollow noopener\" target=\"_blank\" style=\"font-size:32px!important;box-shadow:none;display:inline-block;vertical-align:middle\"><span class=\"heateor_sss_svg\" style=\"background-color:#53beee;width:23px;height:23px;border-radius:999px;display:inline-block;opacity:1;float:left;font-size:32px;box-shadow:none;display:inline-block;font-size:16px;padding:0 4px;vertical-align:middle;background-repeat:repeat;overflow:hidden;padding:0;cursor:pointer;box-sizing:content-box\"><svg style=\"display:block;border-radius:999px;\" version=\"1.1\" viewbox=\"-10 -10 148 148\" width=\"100%\" height=\"100%\" xml:space=\"preserve\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\"><g><g><path d=\"M86,112H42c-14.336,0-26-11.663-26-26V42c0-14.337,11.664-26,26-26h44c14.337,0,26,11.663,26,26v44 C112,100.337,100.337,112,86,112z M42,24c-9.925,0-18,8.074-18,18v44c0,9.925,8.075,18,18,18h44c9.926,0,18-8.075,18-18V42 c0-9.926-8.074-18-18-18H42z\" fill=\"#fff\"><\/path><\/g><g><path d=\"M64,88c-13.234,0-24-10.767-24-24c0-13.234,10.766-24,24-24s24,10.766,24,24C88,77.233,77.234,88,64,88z M64,48c-8.822,0-16,7.178-16,16s7.178,16,16,16c8.822,0,16-7.178,16-16S72.822,48,64,48z\" fill=\"#fff\"><\/path><\/g><g><circle cx=\"89.5\" cy=\"38.5\" fill=\"#fff\" r=\"5.5\"><\/circle><\/g><\/g><\/svg><\/span><\/a><a aria-label=\"Linkedin\" class=\"heateor_sss_button_linkedin\" href=\"https:\/\/www.linkedin.com\/sharing\/share-offsite\/?url=https%3A%2F%2Flobbywatch.ch%2Ffr%2Fmitgliedschaft%2F\" title=\"Linkedin\" rel=\"nofollow noopener\" target=\"_blank\" style=\"font-size:32px!important;box-shadow:none;display:inline-block;vertical-align:middle\"><span class=\"heateor_sss_svg heateor_sss_s__default heateor_sss_s_linkedin\" style=\"background-color:#0077b5;width:23px;height:23px;border-radius:999px;display:inline-block;opacity:1;float:left;font-size:32px;box-shadow:none;display:inline-block;font-size:16px;padding:0 4px;vertical-align:middle;background-repeat:repeat;overflow:hidden;padding:0;cursor:pointer;box-sizing:content-box\"><svg style=\"display:block;border-radius:999px;\" focusable=\"false\" aria-hidden=\"true\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"100%\" height=\"100%\" viewbox=\"0 0 32 32\"><path d=\"M6.227 12.61h4.19v13.48h-4.19V12.61zm2.095-6.7a2.43 2.43 0 0 1 0 4.86c-1.344 0-2.428-1.09-2.428-2.43s1.084-2.43 2.428-2.43m4.72 6.7h4.02v1.84h.058c.56-1.058 1.927-2.176 3.965-2.176 4.238 0 5.02 2.792 5.02 6.42v7.395h-4.183v-6.56c0-1.564-.03-3.574-2.178-3.574-2.18 0-2.514 1.7-2.514 3.46v6.668h-4.187V12.61z\" fill=\"#fff\"><\/path><\/svg><\/span><\/a><a aria-label=\"Mastodon\" class=\"heateor_sss_button_mastodon\" href=\"https:\/\/mastodon.social\/share?text=https%3A%2F%2Flobbywatch.ch%2Ffr%2Fmitgliedschaft%2F&title=Mitgliedschaft\" title=\"Mastodon\" rel=\"nofollow noopener\" target=\"_blank\" style=\"font-size:32px!important;box-shadow:none;display:inline-block;vertical-align:middle\"><span class=\"heateor_sss_svg heateor_sss_s__default heateor_sss_s_mastodon\" style=\"background-color:#6364FF;width:23px;height:23px;border-radius:999px;display:inline-block;opacity:1;float:left;font-size:32px;box-shadow:none;display:inline-block;font-size:16px;padding:0 4px;vertical-align:middle;background-repeat:repeat;overflow:hidden;padding:0;cursor:pointer;box-sizing:content-box\"><svg style=\"display:block;border-radius:999px;\" focusable=\"false\" aria-hidden=\"true\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"100%\" height=\"100%\" viewbox=\"-3.5 -3.5 39 39\"><path d=\"M27 12c0-5.12-3.35-6.62-3.35-6.62C22 4.56 19.05 4.23 16 4.21c-3 0-5.92.35-7.61 1.12C8.36 5.33 5 6.83 5 12v4c.12 5 .92 9.93 5.54 11.16a17.67 17.67 0 005.44.6 10.88 10.88 0 004.18-.95l-.09-1.95a13.36 13.36 0 01-4.07.54c-2.12-.07-4.37-.23-4.71-2.84a5.58 5.58 0 01-.05-.73 27.46 27.46 0 004.73.63 26.76 26.76 0 004.68-.28c3-.35 5.53-2.17 5.85-3.83A39.25 39.25 0 0027 12zm-3.95 6.59h-2.46v-6c0-1.27-.53-1.91-1.6-1.91s-1.77.76-1.77 2.27v3.29h-2.44v-3.35c0-1.51-.59-2.27-1.77-2.27s-1.6.64-1.6 1.91v6H9v-6.18a4.49 4.49 0 011-3 3.39 3.39 0 012.63-1.12 3.17 3.17 0 012.84 1.44l.61 1 .61-1a3.17 3.17 0 012.84-1.44 3.39 3.39 0 012.63 1.12 4.49 4.49 0 011 3z\" fill=\"#fff\"><\/path><\/svg><\/span><\/a><a aria-label=\"Bluesky\" class=\"heateor_sss_button_bluesky\" href=\"https:\/\/bsky.app\/intent\/compose?text=Mitgliedschaft%20https%3A%2F%2Flobbywatch.ch%2Ffr%2Fmitgliedschaft%2F\" title=\"Bluesky\" rel=\"nofollow noopener\" target=\"_blank\" style=\"font-size:32px!important;box-shadow:none;display:inline-block;vertical-align:middle\"><span class=\"heateor_sss_svg heateor_sss_s__default heateor_sss_s_bluesky\" style=\"background-color:#0085ff;width:23px;height:23px;border-radius:999px;display:inline-block;opacity:1;float:left;font-size:32px;box-shadow:none;display:inline-block;font-size:16px;padding:0 4px;vertical-align:middle;background-repeat:repeat;overflow:hidden;padding:0;cursor:pointer;box-sizing:content-box\"><svg width=\"100%\" height=\"100%\" style=\"display:block;border-radius:999px;\" focusable=\"false\" aria-hidden=\"true\" viewbox=\"-3 -3 38 38\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M16 14.903c-.996-1.928-3.709-5.521-6.231-7.293C7.353 5.912 6.43 6.206 5.827 6.478 5.127 6.793 5 7.861 5 8.49s.346 5.155.572 5.91c.747 2.496 3.404 3.34 5.851 3.07.125-.02.252-.036.38-.052-.126.02-.253.037-.38.051-3.586.529-6.771 1.83-2.594 6.457 4.595 4.735 6.297-1.015 7.171-3.93.874 2.915 1.88 8.458 7.089 3.93 3.911-3.93 1.074-5.928-2.512-6.457a8.122 8.122 0 0 1-.38-.051c.128.016.255.033.38.051 2.447.271 5.104-.573 5.85-3.069.227-.755.573-5.281.573-5.91 0-.629-.127-1.697-.827-2.012-.604-.271-1.526-.566-3.942 1.132-2.522 1.772-5.235 5.365-6.231 7.293Z\" fill=\"#fff\"\/><\/svg><\/span><\/a><a aria-label=\"Email\" class=\"heateor_sss_email\" href=\"https:\/\/lobbywatch.ch\/fr\/mitgliedschaft\/\" onclick=\"event.preventDefault();window.open('mailto:?subject=' + decodeURIComponent('Mitgliedschaft').replace('&', '%26') + '&body=https%3A%2F%2Flobbywatch.ch%2Ffr%2Fmitgliedschaft%2F', '_blank')\" title=\"Email\" rel=\"noopener\" style=\"font-size:32px!important;box-shadow:none;display:inline-block;vertical-align:middle\"><span class=\"heateor_sss_svg\" style=\"background-color:#649a3f;width:23px;height:23px;border-radius:999px;display:inline-block;opacity:1;float:left;font-size:32px;box-shadow:none;display:inline-block;font-size:16px;padding:0 4px;vertical-align:middle;background-repeat:repeat;overflow:hidden;padding:0;cursor:pointer;box-sizing:content-box\"><svg style=\"display:block;border-radius:999px;\" focusable=\"false\" aria-hidden=\"true\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"100%\" height=\"100%\" viewbox=\"-.75 -.5 36 36\"><path d=\"M 5.5 11 h 23 v 1 l -11 6 l -11 -6 v -1 m 0 2 l 11 6 l 11 -6 v 11 h -22 v -11\" stroke-width=\"1\" fill=\"#fff\"><\/path><\/svg><\/span><\/a><\/div><div class=\"heateorSssClear\"><\/div><\/div>\n\t\t<\/div>\n\t<\/div>\n<div class=\"divider-wrap\" data-alignment=\"default\"><div style=\"height: 30px;\" class=\"divider\"><\/div><\/div>\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n<\/div><\/div>\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div>","protected":false},"excerpt":{"rendered":"Toll, st\u00e4rken Sie das Gegengewicht zur Lobbymacht. Spenden Mitgliedschaft Mithelfen Spenden Mitgliedschaft Mithelfen Mitglieder sichern unsere Unabh\u00e4ngigkeit und erm\u00f6glichen hartn\u00e4ckige Recherchen. Je mehr wir sind, desto st\u00e4rker unsere Stimme fu\u0308r...","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"categories":[],"tags":[],"class_list":["post-8188","page","type-page","status-publish"],"_links":{"self":[{"href":"https:\/\/lobbywatch.ch\/fr\/wp-json\/wp\/v2\/pages\/8188","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lobbywatch.ch\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/lobbywatch.ch\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/lobbywatch.ch\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/lobbywatch.ch\/fr\/wp-json\/wp\/v2\/comments?post=8188"}],"version-history":[{"count":48,"href":"https:\/\/lobbywatch.ch\/fr\/wp-json\/wp\/v2\/pages\/8188\/revisions"}],"predecessor-version":[{"id":8798,"href":"https:\/\/lobbywatch.ch\/fr\/wp-json\/wp\/v2\/pages\/8188\/revisions\/8798"}],"wp:attachment":[{"href":"https:\/\/lobbywatch.ch\/fr\/wp-json\/wp\/v2\/media?parent=8188"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lobbywatch.ch\/fr\/wp-json\/wp\/v2\/categories?post=8188"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lobbywatch.ch\/fr\/wp-json\/wp\/v2\/tags?post=8188"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}